{"id":33871,"date":"2022-10-23T17:23:29","date_gmt":"2022-10-23T15:23:29","guid":{"rendered":"https:\/\/ulysseus.eu\/?page_id=33871"},"modified":"2024-10-15T13:09:46","modified_gmt":"2024-10-15T11:09:46","slug":"goals","status":"publish","type":"page","link":"https:\/\/ulysseus.eu\/sk\/goals\/","title":{"rendered":"Goals"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-33871","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Goals - Ulysseus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ulysseus.eu\/sk\/goals\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Goals - Ulysseus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ulysseus.eu\/sk\/goals\/\" \/>\n<meta property=\"og:site_name\" content=\"Ulysseus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-15T11:09:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/goals\\\/\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/goals\\\/\",\"name\":\"Goals - Ulysseus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/#website\"},\"datePublished\":\"2022-10-23T15:23:29+00:00\",\"dateModified\":\"2024-10-15T11:09:46+00:00\",\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/goals\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/#website\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/\",\"name\":\"Ulysseus\",\"description\":\"European University\",\"publisher\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk-SK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/#organization\",\"name\":\"Ulysseus\",\"alternateName\":\"European University\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ulysseus-Logo-01-MainVersion-2.png\",\"contentUrl\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ulysseus-Logo-01-MainVersion-2.png\",\"width\":3508,\"height\":2481,\"caption\":\"Ulysseus\"},\"image\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/sk\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UlysseusEuropeanUniversity\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ulysseus_eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Goals - Ulysseus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ulysseus.eu\/sk\/goals\/","og_locale":"sk_SK","og_type":"article","og_title":"Goals - Ulysseus","og_url":"https:\/\/ulysseus.eu\/sk\/goals\/","og_site_name":"Ulysseus","article_publisher":"https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/","article_modified_time":"2024-10-15T11:09:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ulysseus.eu\/sk\/goals\/","url":"https:\/\/ulysseus.eu\/sk\/goals\/","name":"Goals - Ulysseus","isPartOf":{"@id":"https:\/\/ulysseus.eu\/sk\/#website"},"datePublished":"2022-10-23T15:23:29+00:00","dateModified":"2024-10-15T11:09:46+00:00","inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ulysseus.eu\/sk\/goals\/"]}]},{"@type":"WebSite","@id":"https:\/\/ulysseus.eu\/sk\/#website","url":"https:\/\/ulysseus.eu\/sk\/","name":"Ulysseus","description":"European University","publisher":{"@id":"https:\/\/ulysseus.eu\/sk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ulysseus.eu\/sk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk-SK"},{"@type":"Organization","@id":"https:\/\/ulysseus.eu\/sk\/#organization","name":"Ulysseus","alternateName":"European University","url":"https:\/\/ulysseus.eu\/sk\/","logo":{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/ulysseus.eu\/sk\/#\/schema\/logo\/image\/","url":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2022\/02\/Ulysseus-Logo-01-MainVersion-2.png","contentUrl":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2022\/02\/Ulysseus-Logo-01-MainVersion-2.png","width":3508,"height":2481,"caption":"Ulysseus"},"image":{"@id":"https:\/\/ulysseus.eu\/sk\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/","https:\/\/www.instagram.com\/ulysseus_eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/ulysseus.eu\/sk\/wp-json\/wp\/v2\/pages\/33871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ulysseus.eu\/sk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ulysseus.eu\/sk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ulysseus.eu\/sk\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ulysseus.eu\/sk\/wp-json\/wp\/v2\/comments?post=33871"}],"version-history":[{"count":5,"href":"https:\/\/ulysseus.eu\/sk\/wp-json\/wp\/v2\/pages\/33871\/revisions"}],"predecessor-version":[{"id":46705,"href":"https:\/\/ulysseus.eu\/sk\/wp-json\/wp\/v2\/pages\/33871\/revisions\/46705"}],"wp:attachment":[{"href":"https:\/\/ulysseus.eu\/sk\/wp-json\/wp\/v2\/media?parent=33871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}