{"id":72430,"date":"2024-09-04T09:56:24","date_gmt":"2024-09-04T07:56:24","guid":{"rendered":"https:\/\/ulysseus.eu\/?post_type=resources&#038;p=72430"},"modified":"2024-09-06T12:34:05","modified_gmt":"2024-09-06T10:34:05","slug":"compass-useful-resources-supporting-open-science","status":"publish","type":"resources","link":"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/","title":{"rendered":"COMPASS Useful  resources supporting Open Science"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">The COMPASS project represents a large-scale initiative aimed at promoting open science across Europe. As part of this project, we have compiled a comprehensive list of essential resources designed to support transparent and collaborative research practices. These resources, developed primarily by the European Commission as well as other European projects within the Ulysseus consortium, are intended to facilitate access to information, promote open access to scientific publications and research data, and encourage collaboration within the scientific community.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>This article explores three main categories of resources: those developed by the European Commission, those stemming from Ulysseus consortium members&#8217; projects, and those originating from national and international initiatives supporting open science. By examining these resources, we aim to identify how they can help researchers maximize the impact of their work while meeting the requirements of European Union-funded projects.<\/p>\n","protected":false},"featured_media":72454,"template":"","tags":[41,409],"class_list":["post-72430","resources","type-resources","status-publish","has-post-thumbnail","hentry","tag-compass","tag-open-science"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMPASS Useful resources supporting Open Science - Ulysseus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMPASS Useful resources supporting Open Science - Ulysseus\" \/>\n<meta property=\"og:description\" content=\"The COMPASS project represents a large-scale initiative aimed at promoting open science across Europe. As part of this project, we have compiled a comprehensive list of essential resources designed to support transparent and collaborative research practices. These resources, developed primarily by the European Commission as well as other European projects within the Ulysseus consortium, are [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/\" \/>\n<meta property=\"og:site_name\" content=\"Ulysseus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-06T10:34:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ulysseus.eu\/wp-content\/uploads\/2024\/09\/Open-Science-Resources.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"1018\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Arvioitu lukuaika\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuutti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/resources-and-publications\\\/compass-useful-resources-supporting-open-science\\\/\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/resources-and-publications\\\/compass-useful-resources-supporting-open-science\\\/\",\"name\":\"COMPASS Useful resources supporting Open Science - Ulysseus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/resources-and-publications\\\/compass-useful-resources-supporting-open-science\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/resources-and-publications\\\/compass-useful-resources-supporting-open-science\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Open-Science-Resources.jpg\",\"datePublished\":\"2024-09-04T07:56:24+00:00\",\"dateModified\":\"2024-09-06T10:34:05+00:00\",\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/resources-and-publications\\\/compass-useful-resources-supporting-open-science\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/resources-and-publications\\\/compass-useful-resources-supporting-open-science\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Open-Science-Resources.jpg\",\"contentUrl\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Open-Science-Resources.jpg\",\"width\":720,\"height\":1018,\"caption\":\"Useful resources supporting Open Science cover\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/#website\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/\",\"name\":\"Ulysseus\",\"description\":\"European University\",\"publisher\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/#organization\",\"name\":\"Ulysseus\",\"alternateName\":\"European University\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ulysseus-Logo-01-MainVersion-2.png\",\"contentUrl\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ulysseus-Logo-01-MainVersion-2.png\",\"width\":3508,\"height\":2481,\"caption\":\"Ulysseus\"},\"image\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/fi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UlysseusEuropeanUniversity\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ulysseus_eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMPASS Useful resources supporting Open Science - Ulysseus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/","og_locale":"fi_FI","og_type":"article","og_title":"COMPASS Useful resources supporting Open Science - Ulysseus","og_description":"The COMPASS project represents a large-scale initiative aimed at promoting open science across Europe. As part of this project, we have compiled a comprehensive list of essential resources designed to support transparent and collaborative research practices. These resources, developed primarily by the European Commission as well as other European projects within the Ulysseus consortium, are [&hellip;]","og_url":"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/","og_site_name":"Ulysseus","article_publisher":"https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/","article_modified_time":"2024-09-06T10:34:05+00:00","og_image":[{"width":720,"height":1018,"url":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2024\/09\/Open-Science-Resources.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Arvioitu lukuaika":"1 minuutti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/","url":"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/","name":"COMPASS Useful resources supporting Open Science - Ulysseus","isPartOf":{"@id":"https:\/\/ulysseus.eu\/fi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/#primaryimage"},"image":{"@id":"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/#primaryimage"},"thumbnailUrl":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2024\/09\/Open-Science-Resources.jpg","datePublished":"2024-09-04T07:56:24+00:00","dateModified":"2024-09-06T10:34:05+00:00","inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/ulysseus.eu\/fi\/resources-and-publications\/compass-useful-resources-supporting-open-science\/#primaryimage","url":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2024\/09\/Open-Science-Resources.jpg","contentUrl":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2024\/09\/Open-Science-Resources.jpg","width":720,"height":1018,"caption":"Useful resources supporting Open Science cover"},{"@type":"WebSite","@id":"https:\/\/ulysseus.eu\/fi\/#website","url":"https:\/\/ulysseus.eu\/fi\/","name":"Ulysseus","description":"European University","publisher":{"@id":"https:\/\/ulysseus.eu\/fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ulysseus.eu\/fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/ulysseus.eu\/fi\/#organization","name":"Ulysseus","alternateName":"European University","url":"https:\/\/ulysseus.eu\/fi\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/ulysseus.eu\/fi\/#\/schema\/logo\/image\/","url":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2022\/02\/Ulysseus-Logo-01-MainVersion-2.png","contentUrl":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2022\/02\/Ulysseus-Logo-01-MainVersion-2.png","width":3508,"height":2481,"caption":"Ulysseus"},"image":{"@id":"https:\/\/ulysseus.eu\/fi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/","https:\/\/www.instagram.com\/ulysseus_eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/ulysseus.eu\/fi\/wp-json\/wp\/v2\/resources\/72430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ulysseus.eu\/fi\/wp-json\/wp\/v2\/resources"}],"about":[{"href":"https:\/\/ulysseus.eu\/fi\/wp-json\/wp\/v2\/types\/resources"}],"version-history":[{"count":5,"href":"https:\/\/ulysseus.eu\/fi\/wp-json\/wp\/v2\/resources\/72430\/revisions"}],"predecessor-version":[{"id":72941,"href":"https:\/\/ulysseus.eu\/fi\/wp-json\/wp\/v2\/resources\/72430\/revisions\/72941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ulysseus.eu\/fi\/wp-json\/wp\/v2\/media\/72454"}],"wp:attachment":[{"href":"https:\/\/ulysseus.eu\/fi\/wp-json\/wp\/v2\/media?parent=72430"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ulysseus.eu\/fi\/wp-json\/wp\/v2\/tags?post=72430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}