{"id":51147,"date":"2023-03-21T11:28:02","date_gmt":"2023-03-21T10:28:02","guid":{"rendered":"https:\/\/ulysseus.eu\/news\/ulysseus-startet-match4cooperation-das-soziale-netzwerk-zur-vernetzung-von-forschenden-in-der-allianz\/"},"modified":"2023-03-29T10:14:34","modified_gmt":"2023-03-29T08:14:34","slug":"ulysseus-startet-match4cooperation","status":"publish","type":"news","link":"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/","title":{"rendered":"Ulysseus startet Match4Cooperation, das soziale Netzwerk zur Vernetzung von Forschenden in der Allianz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Anl\u00e4sslich des Treffens in Nizza stellt die Ulysseus European University ihr neues soziales Netzwerk f\u00fcr Forschende vor: Match4Cooperation (M4C), ein Open-Source-Tool, das als soziales Netzwerk alle Hochschulmitarbeitenden von Ulysseus miteinander verbinden, das Bewusstsein f\u00fcr EU-Forschungsprojektausschreibungen sch\u00e4rfen und die Forschungsmobilit\u00e4t innerhalb von Ulysseus f\u00f6rdern soll. <\/p>\n\n<p class=\"wp-block-paragraph\"><span class=\"TextRun SCXW8279204 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW8279204 BCX9\">Die sechs Partneruniversit\u00e4ten (Universit\u00e4t Sevilla; Universit\u00e4t Genua; <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW8279204 BCX9\">Universit\u00e9<\/span> <span class=\"NormalTextRun SpellingErrorV2Themed SCXW8279204 BCX9\">Cot\u00ea<\/span> <span class=\"NormalTextRun SCXW8279204 BCX9\">D&#8217;Azur<\/span><span class=\"NormalTextRun SCXW8279204 BCX9\">; Technische Universit\u00e4t Ko\u0161ice; MCI | The <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW8279204 BCX9\">Entrepreneurial<\/span><span class=\"NormalTextRun SCXW8279204 BCX9\"> School und Haaga-Helia University of Applied <\/span><span class=\"NormalTextRun SCXW8279204 BCX9\">Sciences<\/span><span class=\"NormalTextRun SCXW8279204 BCX9\">) und die Vertretungen der neuen Partner, die sich Ulysseus im Rahmen des n\u00e4chsten Erasmus+ 2023-Antrags anschlie\u00dfen werden (Universit\u00e4t M\u00fcnster und Universit\u00e4t Montenegro), erfuhren heute am ersten Arbeitstag des Gipfels in Nizza, wie M4C funktioniert.\u00a0<\/span><\/span><span class=\"EOP SCXW8279204 BCX9\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n\n<p class=\"wp-block-paragraph\">Match4Cooperation, ein soziales Netzwerk, das auf der Technologie und dem Code von Mastodon basiert, erm\u00f6glicht es Forschenden, ihre Arbeit mit anderen zu teilen, auf die Forschungsleistungen der anderen zu reagieren und pers\u00f6nliche Gespr\u00e4che in einer sicheren Umgebung zu f\u00fchren. <\/p>\n\n<p class=\"wp-block-paragraph\">Es gibt zahlreiche soziale Forschungsnetzwerke, die um die Teilnahme und die Aufmerksamkeit von Forschern konkurrieren, aber alle sind in privater Hand und erm\u00f6glichen ein geringes Ma\u00df an Kontrolle und Personalisierung durch die teilnehmenden Einrichtungen. Daher wurde M4C geschaffen, damit sich die akademische Gemeinschaft der Allianz \u00fcber institutionelle und sprachliche Barrieren hinweg so verbunden wie m\u00f6glich f\u00fchlt.  <\/p>\n\n<h2 class=\"wp-block-heading\">Europ\u00e4ische Projekte <\/h2>\n\n<p class=\"wp-block-paragraph\">Ein sehr wichtiger Ma\u00dfstab f\u00fcr den Erfolg von Ulysseus ist die F\u00e4higkeit, auf EU-Ausschreibungen f\u00fcr Forschungsprojekte einzugehen und Erfolge zu erzielen. Um dieses Ziel zu erreichen, nutzen die Innovationszentren und andere Forschungsakteure innerhalb der Allianz die Match4Cooperation-Anwendung, um europ\u00e4ische Ausschreibungen zu kommunizieren, auf die sich die Ulysseus-Community bewerben k\u00f6nnte. <\/p>\n\n<p class=\"wp-block-paragraph\">In diesem Sinne finden die Forschenden auf M4C eine spezielle Gruppe &#8211; @projects &#8211; in der alle offenen Projekte eingesehen, aufgerufen und bearbeitet werden k\u00f6nnen. Die Innovation Hub Officer k\u00f6nnen auch ihre eigenen Projekte ver\u00f6ffentlichen, wenn sie auf der Suche nach Kooperationspartnern sind. <\/p>\n\n<h2 class=\"wp-block-heading\">Open Science Wettbewerb in M4C <\/h2>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/Match4Cooperation-web-2-1024x683.webp\" alt=\"\" class=\"wp-image-50393\" srcset=\"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/Match4Cooperation-web-2-1024x683.webp 1024w, https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/Match4Cooperation-web-2-300x200.webp 300w, https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/Match4Cooperation-web-2-jpg.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Als besonderes Highlight zur Feier des Launches von M4C bietet Ulysseus die M\u00f6glichkeit, zwei junge Forschende zu einer Konferenz ihrer Wahl zu schicken. Einzige Voraussetzung ist, dass sie zum Zeitpunkt der Teilnahme an diesem Wettbewerb als Studierende an einer Hochschule immatrikuliert sind oder ihren Doktortitel innerhalb der letzten 5 Jahre erworben haben. <\/p>\n\n<p class=\"wp-block-paragraph\">Die Teilnehmenden m\u00fcssen in ihrem M4C-Profil einen Link zu einer begutachteten Open-Access-Publikation der letzten drei Jahre ver\u00f6ffentlichen, bei der sie Erst- oder Letztautor sind. Der erste Platz wird durch die Anzahl der Retoots des Postings auf M4C bestimmt, w\u00e4hrend der zweite Platz an die Person geht, deren begutachteter Artikel am h\u00e4ufigsten zitiert wurde. <\/p>\n\n<p class=\"wp-block-paragraph\"><span class=\"TextRun SCXW181593509 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW181593509 BCX9\">Alle Informationen \u00fcber diesen Wettbewerb und M4C finden Sie auf der Ulysseus-Website: <\/span><\/span><a class=\"Hyperlink SCXW181593509 BCX9\" href=\"https:\/\/ulysseus.eu\/es\/match4cooperation\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"TextRun Underlined SCXW181593509 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW181593509 BCX9\" data-ccp-charstyle=\"Hyperlink\">https:\/\/ulysseus.eu\/es\/match4cooperation\/<\/span><\/span><\/a><span class=\"TextRun SCXW181593509 BCX9\" lang=\"DE-DE\" xml:lang=\"DE-DE\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW181593509 BCX9\">.<\/span><\/span><span class=\"EOP SCXW181593509 BCX9\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch2-682x1024.webp\" alt=\"\" class=\"wp-image-50434\" srcset=\"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch2-682x1024.webp 682w, https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch2-200x300.webp 200w, https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch2-1023x1536.webp 1023w, https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch2-1200x1802.webp 1200w, https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch2-jpeg.webp 1364w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">\u00dcber Ulysseus<\/h2>\n\n<p class=\"wp-block-paragraph\">Ulysseus ist eine der 44 europ\u00e4ischen Universit\u00e4ten, die von der Europ\u00e4ischen Kommission ausgew\u00e4hlt wurden, um zur Universit\u00e4t der Zukunft zu werden. Das Projekt bestehend aus sechs europ\u00e4ischen Universit\u00e4ten (Universit\u00e4t Sevilla, Spanien; Universit\u00e4t Genua, Italien; Universit\u00e9 C\u00f4te d&#8217;Azur, Frankreich; Technische Universit\u00e4t Ko\u0161ice, Slowakei; MCI | The Entrepreneurial School\u00ae, \u00d6sterreich; und Haaga-Helia University of Applied Sciences, Finnland) wird Studierenden, Forscher:innen und Alumni erm\u00f6glichen, sich frei zwischen den Universit\u00e4ten zu bewegen, Praktika in Unternehmen zu absolvieren und hochwirksame Forschungsprojekte zu starten.<\/p>\n","protected":false},"featured_media":50430,"comment_status":"closed","ping_status":"closed","template":"","tags":[244,247],"class_list":["post-51147","news","type-news","status-publish","has-post-thumbnail","hentry","tag-match4cooperation","tag-researchers"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ulysseus startet Match4Cooperation, das soziale Netzwerk zur Vernetzung von Forschenden in der Allianz - Ulysseus<\/title>\n<meta name=\"description\" content=\"Anl\u00e4sslich des Treffens in Nizza stellt die Ulysseus European University ihr neues soziales Netzwerk f\u00fcr Forschende vor: Match4Cooperation (M4C)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ulysseus startet Match4Cooperation, das soziale Netzwerk zur Vernetzung von Forschenden in der Allianz - Ulysseus\" \/>\n<meta property=\"og:description\" content=\"Anl\u00e4sslich des Treffens in Nizza stellt die Ulysseus European University ihr neues soziales Netzwerk f\u00fcr Forschende vor: Match4Cooperation (M4C)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/\" \/>\n<meta property=\"og:site_name\" content=\"Ulysseus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-29T08:14:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch-jpeg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/news\\\/ulysseus-startet-match4cooperation\\\/\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/news\\\/ulysseus-startet-match4cooperation\\\/\",\"name\":\"Ulysseus startet Match4Cooperation, das soziale Netzwerk zur Vernetzung von Forschenden in der Allianz - Ulysseus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/news\\\/ulysseus-startet-match4cooperation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/news\\\/ulysseus-startet-match4cooperation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/M4C-launch-jpeg.webp\",\"datePublished\":\"2023-03-21T10:28:02+00:00\",\"dateModified\":\"2023-03-29T08:14:34+00:00\",\"description\":\"Anl\u00e4sslich des Treffens in Nizza stellt die Ulysseus European University ihr neues soziales Netzwerk f\u00fcr Forschende vor: Match4Cooperation (M4C)\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ulysseus.eu\\\/de\\\/news\\\/ulysseus-startet-match4cooperation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/news\\\/ulysseus-startet-match4cooperation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/M4C-launch-jpeg.webp\",\"contentUrl\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/M4C-launch-jpeg.webp\",\"width\":2048,\"height\":1364,\"caption\":\"M4C presentation during the Summit in Nice\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/\",\"name\":\"Ulysseus\",\"description\":\"European University\",\"publisher\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/#organization\",\"name\":\"Ulysseus\",\"alternateName\":\"European University\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ulysseus-Logo-01-MainVersion-2.png\",\"contentUrl\":\"https:\\\/\\\/ulysseus.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Ulysseus-Logo-01-MainVersion-2.png\",\"width\":3508,\"height\":2481,\"caption\":\"Ulysseus\"},\"image\":{\"@id\":\"https:\\\/\\\/ulysseus.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/UlysseusEuropeanUniversity\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ulysseus_eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ulysseus startet Match4Cooperation, das soziale Netzwerk zur Vernetzung von Forschenden in der Allianz - Ulysseus","description":"Anl\u00e4sslich des Treffens in Nizza stellt die Ulysseus European University ihr neues soziales Netzwerk f\u00fcr Forschende vor: Match4Cooperation (M4C)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/","og_locale":"de_DE","og_type":"article","og_title":"Ulysseus startet Match4Cooperation, das soziale Netzwerk zur Vernetzung von Forschenden in der Allianz - Ulysseus","og_description":"Anl\u00e4sslich des Treffens in Nizza stellt die Ulysseus European University ihr neues soziales Netzwerk f\u00fcr Forschende vor: Match4Cooperation (M4C)","og_url":"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/","og_site_name":"Ulysseus","article_publisher":"https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/","article_modified_time":"2023-03-29T08:14:34+00:00","og_image":[{"width":2048,"height":1364,"url":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch-jpeg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/","url":"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/","name":"Ulysseus startet Match4Cooperation, das soziale Netzwerk zur Vernetzung von Forschenden in der Allianz - Ulysseus","isPartOf":{"@id":"https:\/\/ulysseus.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/#primaryimage"},"image":{"@id":"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/#primaryimage"},"thumbnailUrl":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch-jpeg.webp","datePublished":"2023-03-21T10:28:02+00:00","dateModified":"2023-03-29T08:14:34+00:00","description":"Anl\u00e4sslich des Treffens in Nizza stellt die Ulysseus European University ihr neues soziales Netzwerk f\u00fcr Forschende vor: Match4Cooperation (M4C)","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ulysseus.eu\/de\/news\/ulysseus-startet-match4cooperation\/#primaryimage","url":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch-jpeg.webp","contentUrl":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2023\/03\/M4C-launch-jpeg.webp","width":2048,"height":1364,"caption":"M4C presentation during the Summit in Nice"},{"@type":"WebSite","@id":"https:\/\/ulysseus.eu\/de\/#website","url":"https:\/\/ulysseus.eu\/de\/","name":"Ulysseus","description":"European University","publisher":{"@id":"https:\/\/ulysseus.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ulysseus.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/ulysseus.eu\/de\/#organization","name":"Ulysseus","alternateName":"European University","url":"https:\/\/ulysseus.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/ulysseus.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2022\/02\/Ulysseus-Logo-01-MainVersion-2.png","contentUrl":"https:\/\/ulysseus.eu\/wp-content\/uploads\/2022\/02\/Ulysseus-Logo-01-MainVersion-2.png","width":3508,"height":2481,"caption":"Ulysseus"},"image":{"@id":"https:\/\/ulysseus.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/UlysseusEuropeanUniversity\/","https:\/\/www.instagram.com\/ulysseus_eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/news\/51147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/types\/news"}],"replies":[{"embeddable":true,"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/comments?post=51147"}],"version-history":[{"count":1,"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/news\/51147\/revisions"}],"predecessor-version":[{"id":51148,"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/news\/51147\/revisions\/51148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/media\/50430"}],"wp:attachment":[{"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/media?parent=51147"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ulysseus.eu\/de\/wp-json\/wp\/v2\/tags?post=51147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}